{"id":4015,"date":"2026-02-06T11:33:02","date_gmt":"2026-02-06T14:33:02","guid":{"rendered":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/?post_type=cursos&#038;p=4015"},"modified":"2026-03-27T09:54:27","modified_gmt":"2026-03-27T12:54:27","slug":"entrenamiento-para-el-personal-docente-de-la-unne-en-el-sistema-de-gestion-de-concursos-y-evaluacion-de-desempeno-sigeced","status":"publish","type":"cursos","link":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/cursos\/entrenamiento-para-el-personal-docente-de-la-unne-en-el-sistema-de-gestion-de-concursos-y-evaluacion-de-desempeno-sigeced\/","title":{"rendered":"Entrenamiento para el personal docente de la UNNE en el Sistema de Gesti\u00f3n de Concursos y Evaluaci\u00f3n de Desempe\u00f1o (SIGECED)"},"content":{"rendered":"\n<p class=\"has-background\" style=\"background-color:#e9f4f4\">\ud83d\udcda <strong>Curso Autoasistido \u2013<\/strong> NIVEL 1 Aspirantes inicia 13 abril <\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#e9f4f4\">\u2705 Organiz\u00e1 tu recorrido, acced\u00e9 a los contenidos cuando lo necesites, avanz\u00e1 a tu propio ritmo y descarg\u00e1 tu certificado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>si ya posee <strong>usuario<\/strong>, ingrese a la <strong>plataforma<\/strong> <strong>UNNE Global<\/strong> con su mismo usuario y clave de siempre, a trav\u00e9s de logo de UNNE Global ubicado en la parte superior derecha del sitio.<\/td><td>Si no posee usuario, deber\u00e1 crearse una cuenta a trav\u00e9s del bot\u00f3n <strong>&#8220;Crear nueva cuenta&#8221;<\/strong> del formulario que aparecer\u00e1 haciendo clic sobre el logo de UNNE Global, ubicado en la parte superior derecha del sitio.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color\" style=\"color:#066d75\"><strong>Destinatarios<\/strong> <\/h2>\n\n\n\n<p>Destinado al personal docente de la UNNE que haya sido convocado como evaluador para el a\u00f1o 2026 en llamados a concursos y procesos de carrera docente de la Universidad, mediante el Sistema de Gesti\u00f3n de Concursos y Evaluaci\u00f3n de Desempe\u00f1o Docente (SIGECED), y que haya realizado previamente el Entrenamiento Nivel 1: Aspirantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color\" style=\"color:#066d75\"><strong>Fundamentaci\u00f3<\/strong>n<\/h2>\n\n\n\n<p>La implementaci\u00f3n del Sistema de Gesti\u00f3n de Concursos y Evaluaci\u00f3n de Desempe\u00f1o (SIGECED) se enmarca en las pol\u00edticas de modernizaci\u00f3n de la gesti\u00f3n universitaria establecidas por el \u201cSistema de Innovaci\u00f3n Estrat\u00e9gica de la UNNE\u201d, aprobado por la Resoluci\u00f3n N\u00b0323\/22 C.S. y las dem\u00e1s normativas internas de la UNNE, dictadas en consecuencia, que promueven la despapelizaci\u00f3n y el uso de Tecnolog\u00edas de la Informaci\u00f3n y de las Comunicaciones (TIC), como as\u00ed tambi\u00e9n la Resoluci\u00f3n RES-2024-1272-REC#UNNE que dispone la utilizaci\u00f3n del \u201cSistema \u00danico de Gesti\u00f3n Integral de Documentaci\u00f3n Universitaria\u201d (&#8220;SUDOCU&#8221;), como \u00fanico soporte de tramitaci\u00f3n de las actuaciones administrativas que se generen en el \u00e1mbito de la Universidad, constituyendo las mismas el fundamento legal para adoptar herramientas como el expediente electr\u00f3nico, dotando al tr\u00e1mite de mayor agilidad y trazabilidad.<\/p>\n\n\n\n<p>La propuesta de formaci\u00f3n se compone de dos cursos,  que surgen desde la Secretar\u00eda Gral Acad\u00e9mica y&nbsp; tiene como prop\u00f3sito ofrecer a todo el personal docente de la UNNE instancias formativas para la socializaci\u00f3n y el entrenamiento del sistema desde el cual se podr\u00e1 gestionar los procesos de concursos docentes, evaluaci\u00f3n de carrera docente y mayor dedicaci\u00f3n en el \u00e1mbito de la UNNE, en todos sus roles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-verde-056168-color has-text-color\">Tipos de destinatarios:<\/h2>\n\n\n\n<p><strong>En Nivel 1<\/strong>: Aspirantes. <strong>Clave de auto matriculaci\u00f3n ASP2<\/strong><\/p>\n\n\n\n<p> Se ejercitan&nbsp; los procedimientos necesarios para concursar en cargos docentes de la UNNE y realizar todo el tr\u00e1mite correspondiente a la inscripci\u00f3n de&nbsp; convocatorias a concursos docentes.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/virtual-mooc.unne.edu.ar\/course\/view.php?id=3817\" style=\"color:#f3f7f7;background-color:#066d75\">QUIERO HACER ESTE CURSO <\/a><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th>Contenidos Nivel 1.<\/th><\/tr><\/thead><tbody><tr><td><strong>M\u00f3dulo 1<\/strong>: Acceso al sistema y Gesti\u00f3n del usuario <br><br><strong>M\u00f3dulo 2: <\/strong>Proceso de inscripci\u00f3n <br><\/td><\/tr><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>En el Nivel 2<\/strong>: Evaluadores. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> Se ejercitan los procedimientos que deber\u00e1n realizar los jurados en los&nbsp; concursos docentes desde el registro al sistema como elevaci\u00f3n de dict\u00e1menes de concursos o carrera docente.&nbsp;<\/p>\n\n\n\n<p><strong>Aclaraci\u00f3n<\/strong>: Se puede realizar el Nivel 2 sin haber realizado el Nivel 1. <\/p>\n\n\n\n<p><strong>Objetivo<\/strong>s <strong>de aprendizaje<\/strong><\/p>\n\n\n\n<p><strong>General:<\/strong><br>Brindar un entrenamiento del SIGECED para la gesti\u00f3n de todas las etapas de los procesos de concursos docentes, evaluaci\u00f3n de carrera docente y mayor dedicaci\u00f3n en el \u00e1mbito de la UNNE.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th>Contenidos Nivel 2.<\/th><\/tr><\/thead><tbody><tr><td><strong>M\u00f3dulo 1<\/strong>: Normativas.<br><br><strong>M\u00f3dulo 2: <\/strong>Registro y acceso al Sistema. <br><br><strong>M\u00f3dulo 3:<\/strong> Pr\u00e1ctica de evaluaci\u00f3n de llamado a concurso y carrera docente<br><br><strong>M\u00f3dulo 4:<\/strong> Dictamen. Ampliaci\u00f3n de Dictamen<\/td><\/tr><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Responsables<\/strong><\/p>\n\n\n\n<p><strong>Secretaria General Acad\u00e9mica<\/strong>:<\/p>\n\n\n\n<p>Dra. Patricia Demuth Mercado<\/p>\n\n\n\n<p><strong>Subsecretaria<\/strong> <strong>de Asuntos Acad\u00e9micos<\/strong><\/p>\n\n\n\n<p>Prof. Alejandra Hernando<\/p>\n\n\n\n<p><strong>Respensables Direcci\u00f3n de Gesti\u00f3n e Innovaci\u00f3n de las Tecnolog\u00eda de la Informaci\u00f3n<\/strong><\/p>\n\n\n\n<p>Alicia Daverio<\/p>\n\n\n\n<p>Marina Paola Barrios<\/p>\n\n\n\n<p>Vanesa Solange Roffe<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Responsables Sied UNNE Virtual-UNNE Global: <\/strong><\/p>\n\n\n\n<p>Mg. Mar\u00eda Graciela Fern\u00e1ndez<\/p>\n\n\n\n<p>Prof. Fernanda C\u00e1ceres<\/p>\n\n\n\n<p>Dg. Luciana Ramirez Farias<\/p>\n\n\n\n<p>Dg. Ileanda de Le\u00f3n<\/p>\n\n\n\n<p>Lic. Mar\u00eda Isabel S\u00e1nchez<\/p>\n\n\n\n<p>Dg. Luciana Micaela Baez Noguera<\/p>\n\n\n\n<p>Prof. Julian David Vallejos<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-2 wp-block-group-is-layout-flex\">\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-color has-medium-font-size\" style=\"color:#e29506\"><strong>Certificaci\u00f3n que otorga<\/strong><\/p>\n<\/div>\n\n\n\n<p>Se otorgar\u00e1 certificado a los cursantes que hayan finalizado  teniendo aprobadas las actividades propuestas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-verde-056168-background-color has-text-color has-background\" style=\"color:#fbf8f8\">Contacto<\/h4>\n\n\n\n<p>Persona o \u00e1rea de contacto:<\/p>\n\n\n\n<p>Alejandra Hernando: abhernan@exa.unne.edu.ar<\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":4025,"parent":0,"template":"","categorias_cursos":[50],"acf":[],"_links":{"self":[{"href":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/wp-json\/wp\/v2\/cursos\/4015"}],"collection":[{"href":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/wp-json\/wp\/v2\/cursos"}],"about":[{"href":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/wp-json\/wp\/v2\/types\/cursos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/wp-json\/wp\/v2\/media\/4025"}],"wp:attachment":[{"href":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/wp-json\/wp\/v2\/media?parent=4015"}],"wp:term":[{"taxonomy":"categorias_cursos","embeddable":true,"href":"https:\/\/virtual.unne.edu.ar\/SIED-UV\/wp-json\/wp\/v2\/categorias_cursos?post=4015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}